{"id":50222,"date":"2019-09-07T06:00:54","date_gmt":"2019-09-07T04:00:54","guid":{"rendered":"http:\/\/smeupnew.it\/magazine\/blog\/software-personalizzato\/"},"modified":"2019-09-07T06:00:54","modified_gmt":"2019-09-07T04:00:54","slug":"software-personalizzato","status":"publish","type":"post","link":"https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/","title":{"rendered":"Software personalizzato? Puoi ottenerlo grazie alle soluzioni modulari!"},"content":{"rendered":"<p>Immagina due persone completamente diverse che indossano lo stesso identico vestito: come potr\u00e0 calzare a pennello a entrambi? Dalla scelta della taglia a quella del colore, sono molti i fattori che concorrono alla realizzazione del capo d\u2019abbigliamento perfetto.<\/p>\n<p>Cos\u00ec come nella sartoria, anche nell\u2019 ambito del business c\u2019\u00e8 bisogno di questa\u00a0<strong>attenzione al dettaglio<\/strong>. La possibilit\u00e0 di avere un software personalizzato \u00e8 fondamentale per garantire la\u00a0<strong>massima resa del prodotto<\/strong>\u00a0e, di conseguenza, un Return of Investment pi\u00f9 alto.<\/p>\n<p>I software modulari offrono l\u2019opportunit\u00e0 di\u00a0<strong>selezionare solo i moduli davvero utili\u00a0<\/strong>per monitorare i processi fondamentali di un\u2019impresa. Il vantaggio principale che deriva dalla personalizzazione dei gestionali ERP \u00e8 il\u00a0<em>pay-per-use<\/em>: in sostanza l\u2019azienda\u00a0<strong>pagher\u00e0 solo i moduli di cui avr\u00e0 bisogno\u00a0<\/strong>per monitorare i propri processi interni. Ma quali sono i principali servizi modulari associabili a questi software? Vediamoli nei loro settori di applicazione.<\/p>\n<h5>Gestione economica dell\u2019impresa<\/h5>\n<p>L\u2019aspetto finanziario \u00e8 da sempre uno dei processi nevralgici all\u2019interno di un\u2019azienda. Il voler\u00a0<strong>chiudere con un bilancio in positivo<\/strong>\u00a0\u00e8 forse una delle pi\u00f9 grandi preoccupazioni di ogni manager, e per questo motivo sono diverse le soluzioni modulari che il mercato offre. A proposito di bilancio, il primo modulo \u00e8 proprio uno\u00a0<strong>strumento per la sua analisi<\/strong>. Attraverso questo tool si potr\u00e0 determinare facilmente il\u00a0<strong>rating aziendale<\/strong>\u00a0per poi confrontarlo con quello dei settori industriali di vicina competenza.<\/p>\n<p>Altro modulo in ambito finanziario \u00e8 quello che riguarda la\u00a0<strong>valutazione e la\u00a0gestione dei pagamenti e del credito<\/strong>. In un mercato che richiede risposte sempre pi\u00f9 tempestive alle richieste di clienti molto esigenti, uno strumento di questo tipo pu\u00f2 aiutare ad erodere quote di mercato, migliorando le proprie performance. Questo modulo comprende elementi di<strong>\u00a0Business Intelligence\u00a0e di CRM\u00a0<\/strong>(Customer Relationship Management) perch\u00e9 da un lato presenta strumenti per il monitoraggio e l\u2019archiviazione dei dati sensibili dei propri clienti, dall\u2019altro\u00a0<strong>racchiude in s\u00e9 le caratteristiche dei DSS\u00a0<\/strong>(Decision Support System), strumenti informatici in grado di supportare le decisioni manageriali.<\/p>\n<h5>Controllo di produzione e vendita<\/h5>\n<p>Dal punto di vista del processo produttivo, esistono dei moduli in grado di controllare la cosiddetta \u201cmaintenance\u201d, ovvero il\u00a0<strong>funzionamento e la manutenzione delle macchine<\/strong>. Spesso un macchinario poco performante pu\u00f2 portare a sprechi di tempo e denaro: individuare il difetto tempestivamente permette di arginare queste problematiche. In pi\u00f9, \u00e8 possibile\u00a0<strong>migliorare il lavoro in team<\/strong>\u00a0grazie ai moduli per facilitare la comunicazione non solo interna ma anche esterna. Soprattutto nel caso dell\u2019azienda estesa, \u00e8 necessario avere la possibilit\u00e0 di\u00a0<strong>scambiare informazioni di carattere gestionale\u00a0<\/strong>all\u2019interno della\u00a0<em>supply chain<\/em>\u00a0in tempo reale.<\/p>\n<h5>Una documentazione sempre impeccabile<\/h5>\n<p>Quante volte ti \u00e8 capitato di avere urgente bisogno di un vecchio documento ma di non riuscire a trovarlo in tempo utile? La digitalizzazione e<strong>\u00a0la manutenzione informatica degli archivi<\/strong>\u00a0\u00e8 ormai un must per ogni impresa che vuole risultare competitiva sul mercato.\u00a0Alcuni sistemi permettono la\u00a0<strong>creazione di veri e propri\u00a0archivi digitali,\u00a0<\/strong>consentendo di definire alcuni parametri tra cui l\u2019intervallo di conservazione e le date da considerare.\u00a0In pi\u00f9, alcune soluzioni modulari sono\u00a0<strong>accessibili anche da remoto<\/strong>, permettendoti di avere i tuoi dati sempre a portata di click.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I software modulari permettono alle aziende di trovare il software personalizzato che rispecchi le proprie esigenze e consente di acquistare soltanto i moduli necessari. Questo consente alle aziende di ridurre i costi ed ottimizzare la resa del software.<\/p>\n","protected":false},"author":1,"featured_media":50223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[5694,5695,5696,5672,5087,5382,5204,5698,5699],"class_list":["post-50222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-da-smeup","tag-accessibilita-da-remoto","tag-controllo-manutenzione","tag-gestione-degli-archivi","tag-gestione-della-produzione","tag-lavoro-in-team","tag-ottimizzazione-delle-risorse","tag-riduzione-dei-costi","tag-sistemi-modulari","tag-software-personalizzato"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Software personalizzato? Puoi ottenerlo grazie alle soluzioni modulari!<\/title>\n<meta name=\"description\" content=\"I software modulari permettono alle aziende di trovare il software personalizzato che rispecchi le proprie esigenze e consente di acquistare soltanto i moduli necessari. Questo consente alle aziende di ridurre i costi ed ottimizzare la resa del software.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Software personalizzato? Puoi ottenerlo grazie alle soluzioni modulari!\" \/>\n<meta property=\"og:description\" content=\"I software modulari permettono alle aziende di trovare il software personalizzato che rispecchi le proprie esigenze e consente di acquistare soltanto i moduli necessari. Questo consente alle aziende di ridurre i costi ed ottimizzare la resa del software.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/\" \/>\n<meta property=\"og:site_name\" content=\"Magazine\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-07T04:00:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.smeup.com\/magazine\/wp-content\/uploads\/sites\/5\/2021\/03\/software-personalizzato-1024x908.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"908\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"smeup\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"smeup\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/software-personalizzato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/software-personalizzato\\\/\"},\"author\":{\"name\":\"smeup\",\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/#\\\/schema\\\/person\\\/194a55d96e7e52223a84ff78468bf5c7\"},\"headline\":\"Software personalizzato? Puoi ottenerlo grazie alle soluzioni modulari!\",\"datePublished\":\"2019-09-07T04:00:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/software-personalizzato\\\/\"},\"wordCount\":529,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/software-personalizzato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/03\\\/software-personalizzato.png\",\"keywords\":[\"accessibilit\u00e0 da remoto\",\"controllo manutenzione\",\"gestione degli archivi\",\"gestione della produzione\",\"lavoro in team\",\"ottimizzazione delle risorse\",\"riduzione dei costi\",\"sistemi modulari\",\"software personalizzato\"],\"articleSection\":[\"News da smeup\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/software-personalizzato\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/software-personalizzato\\\/\",\"url\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/software-personalizzato\\\/\",\"name\":\"Software personalizzato? Puoi ottenerlo grazie alle soluzioni modulari!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/software-personalizzato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/software-personalizzato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/03\\\/software-personalizzato.png\",\"datePublished\":\"2019-09-07T04:00:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/#\\\/schema\\\/person\\\/194a55d96e7e52223a84ff78468bf5c7\"},\"description\":\"I software modulari permettono alle aziende di trovare il software personalizzato che rispecchi le proprie esigenze e consente di acquistare soltanto i moduli necessari. Questo consente alle aziende di ridurre i costi ed ottimizzare la resa del software.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/software-personalizzato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/software-personalizzato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/software-personalizzato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/03\\\/software-personalizzato.png\",\"contentUrl\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/03\\\/software-personalizzato.png\",\"width\":1600,\"height\":1418},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/software-personalizzato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Software personalizzato? Puoi ottenerlo grazie alle soluzioni modulari!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/#website\",\"url\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/\",\"name\":\"Magazine\",\"description\":\"smeup\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/#\\\/schema\\\/person\\\/194a55d96e7e52223a84ff78468bf5c7\",\"name\":\"smeup\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a88cc3ad6c0af01768fe2ac47c88a321699d97ced53c173f66ceaa51400f43ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a88cc3ad6c0af01768fe2ac47c88a321699d97ced53c173f66ceaa51400f43ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a88cc3ad6c0af01768fe2ac47c88a321699d97ced53c173f66ceaa51400f43ca?s=96&d=mm&r=g\",\"caption\":\"smeup\"},\"sameAs\":[\"https:\\\/\\\/www.smeup.com\"],\"url\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Software personalizzato? Puoi ottenerlo grazie alle soluzioni modulari!","description":"I software modulari permettono alle aziende di trovare il software personalizzato che rispecchi le proprie esigenze e consente di acquistare soltanto i moduli necessari. Questo consente alle aziende di ridurre i costi ed ottimizzare la resa del software.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/","og_locale":"it_IT","og_type":"article","og_title":"Software personalizzato? Puoi ottenerlo grazie alle soluzioni modulari!","og_description":"I software modulari permettono alle aziende di trovare il software personalizzato che rispecchi le proprie esigenze e consente di acquistare soltanto i moduli necessari. Questo consente alle aziende di ridurre i costi ed ottimizzare la resa del software.","og_url":"https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/","og_site_name":"Magazine","article_published_time":"2019-09-07T04:00:54+00:00","og_image":[{"width":1024,"height":908,"url":"https:\/\/www.smeup.com\/magazine\/wp-content\/uploads\/sites\/5\/2021\/03\/software-personalizzato-1024x908.png","type":"image\/png"}],"author":"smeup","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"smeup","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/#article","isPartOf":{"@id":"https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/"},"author":{"name":"smeup","@id":"https:\/\/www.smeup.com\/magazine\/#\/schema\/person\/194a55d96e7e52223a84ff78468bf5c7"},"headline":"Software personalizzato? Puoi ottenerlo grazie alle soluzioni modulari!","datePublished":"2019-09-07T04:00:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/"},"wordCount":529,"commentCount":0,"image":{"@id":"https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smeup.com\/magazine\/wp-content\/uploads\/sites\/5\/2021\/03\/software-personalizzato.png","keywords":["accessibilit\u00e0 da remoto","controllo manutenzione","gestione degli archivi","gestione della produzione","lavoro in team","ottimizzazione delle risorse","riduzione dei costi","sistemi modulari","software personalizzato"],"articleSection":["News da smeup"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/","url":"https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/","name":"Software personalizzato? Puoi ottenerlo grazie alle soluzioni modulari!","isPartOf":{"@id":"https:\/\/www.smeup.com\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/#primaryimage"},"image":{"@id":"https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smeup.com\/magazine\/wp-content\/uploads\/sites\/5\/2021\/03\/software-personalizzato.png","datePublished":"2019-09-07T04:00:54+00:00","author":{"@id":"https:\/\/www.smeup.com\/magazine\/#\/schema\/person\/194a55d96e7e52223a84ff78468bf5c7"},"description":"I software modulari permettono alle aziende di trovare il software personalizzato che rispecchi le proprie esigenze e consente di acquistare soltanto i moduli necessari. Questo consente alle aziende di ridurre i costi ed ottimizzare la resa del software.","breadcrumb":{"@id":"https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/#primaryimage","url":"https:\/\/www.smeup.com\/magazine\/wp-content\/uploads\/sites\/5\/2021\/03\/software-personalizzato.png","contentUrl":"https:\/\/www.smeup.com\/magazine\/wp-content\/uploads\/sites\/5\/2021\/03\/software-personalizzato.png","width":1600,"height":1418},{"@type":"BreadcrumbList","@id":"https:\/\/www.smeup.com\/magazine\/blog\/software-personalizzato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.smeup.com\/magazine\/"},{"@type":"ListItem","position":2,"name":"Software personalizzato? Puoi ottenerlo grazie alle soluzioni modulari!"}]},{"@type":"WebSite","@id":"https:\/\/www.smeup.com\/magazine\/#website","url":"https:\/\/www.smeup.com\/magazine\/","name":"Magazine","description":"smeup","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.smeup.com\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.smeup.com\/magazine\/#\/schema\/person\/194a55d96e7e52223a84ff78468bf5c7","name":"smeup","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a88cc3ad6c0af01768fe2ac47c88a321699d97ced53c173f66ceaa51400f43ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a88cc3ad6c0af01768fe2ac47c88a321699d97ced53c173f66ceaa51400f43ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a88cc3ad6c0af01768fe2ac47c88a321699d97ced53c173f66ceaa51400f43ca?s=96&d=mm&r=g","caption":"smeup"},"sameAs":["https:\/\/www.smeup.com"],"url":"https:\/\/www.smeup.com\/magazine\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/posts\/50222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/comments?post=50222"}],"version-history":[{"count":0,"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/posts\/50222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/media\/50223"}],"wp:attachment":[{"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/media?parent=50222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/categories?post=50222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/tags?post=50222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}