{"id":55557,"date":"2021-11-02T11:20:49","date_gmt":"2021-11-02T10:20:49","guid":{"rendered":"https:\/\/www.smeup.com\/magazine\/?p=55557"},"modified":"2021-12-02T12:20:40","modified_gmt":"2021-12-02T11:20:40","slug":"abolizione-esterometro","status":"publish","type":"post","link":"https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/","title":{"rendered":"Abolizione dell\u2019esterometro: dal 1\u00b0 gennaio cosa cambia"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling gradient-container-1\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:20px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p><strong>A partire dal 1\u00b0 gennaio 2022 l\u2019Esterometro sar\u00e0 abolito<\/strong>, in quanto entrer\u00e0 in vigore l\u2019obbligo di fatturazione elettronica anche per acquisti e vendite con controparti estere. Si tratta di una delle novit\u00e0 previste dalla legge di bilancio del 2021, pi\u00f9 dettagliatamente dell\u2019art. 1, comma 1103, legge n. 178\/2020 che concerne la comunicazione telematica delle operazioni transfrontaliere &#8211; esterometro.<br \/>\nLa trasmissione dei dati della fattura elettronica tramite lo SDI (Sistema di Interscambio), gi\u00e0 obbligatoria in Italia, diventer\u00e0 cos\u00ec <strong>necessaria anche per le fatture relative a operazioni transfrontaliere di cessioni di beni e prestazioni di servizi effettuate (e ricevute) nei confronti di soggetti al di fuori dello Stato.<\/strong><\/p>\n<h1>Cosa prevede la normativa?<\/h1>\n<p>La Legge di Bilancio 2021 (art. 1, comma 1103 della Legge n. 178 del 30 dicembre 2020) ha stabilito che, con riferimento alle operazioni effettuate a decorrere dal 1\u00b0 gennaio 2022, i dati relativi alle cessioni e prestazioni effettuate verso e da soggetti non stabiliti ai fini IVA in Italia andranno trasmessi telematicamente tramite Sistema di Interscambio (SDI), utilizzando il formato XML gi\u00e0 in uso per l\u2019emissione delle fatture elettroniche (versione 1.6.3 del 20 aprile 2020).<\/p>\n<\/div><div class=\"fusion-text fusion-text-2\"><h1>Nuove modalit\u00e0 per le operazioni con l\u2019estero<\/h1>\n<p><strong>1. Come gestire i dati relativi alle cessioni e prestazioni <em>verso i soggetti non stabiliti in Italia<\/em><\/strong><\/p>\n<p>Per quanto riguarda i dati relativi alle cessioni e prestazioni verso i soggetti non stabiliti in Italia dovranno essere generate e trasmesse allo SDI le fatture elettroniche (contenenti le stesse informazioni delle fatture nazionali) verso i clienti esteri. Nella compilazione del tracciato XML, nel \u2018cessionario\/committente\u2019 verranno indicati i dati del cliente estero e nel \u201ccodice destinatario\u201d XXXXXXX. Tali fatture non verranno consegnate dallo SDI al destinatario della fattura, e l\u2019invio al cliente finale continueranno ad avvenire con le modalit\u00e0 gi\u00e0 in uso.<\/p>\n<p>La trasmissione delle fatture estere dovr\u00e0 avvenire entro i termini legislativamente fissati per l\u2019emissione delle altre fatture elettroniche (in linea generale, dodici giorni dalla data di effettuazione dell\u2019operazione o il diverso termine stabilito da specifiche disposizioni come le fatture differite ecc.).<\/p>\n<p><strong>2. Come gestire i dati relativi alle cessioni e prestazioni <em>ricevute da soggetti non stabilit\u00e0 in Italia<\/em><\/strong><\/p>\n<p>Per quanto riguarda i dati relativi alle cessioni e prestazioni ricevute da soggetti non stabilit\u00e0 in Italia, <strong>entro il 15 del mese successivo a quello di ricevimento del documento d\u2019acquisto<\/strong>, dovranno essere generati e trasmessi i documenti integrativi previsti (TD17\/TD18\/TD19) con i quali comunicare allo SDI in formato elettronico l\u2019importo degli acquisti di merci e servizi da fornitori esteri.<\/p>\n<p>Nella compilazione del tracciato XML, nel \u2018cedente\/prestatore\u2019 dovranno essere indicati i dati relativi al fornitore estero e nel \u2018cessionario\/committente\u2019 i dati relativi all\u2019azienda che genera e trasmette il documento integrativo. Tali documenti verranno recapitati dallo SDI nel cassetto fiscale dell\u2019azienda indicata nel \u2018cessionario\/committente\u2019 ma non dovranno essere registrati contabilmente.<\/p>\n<h1>Impatto sulla gestione delle fatture<\/h1>\n<ul>\n<li><strong>emissione fatture attive<\/strong> relative alle operazioni effettuate nei confronti di soggetti non stabiliti in Italia: si dovr\u00e0 emettere una fattura elettronica di tipo TD01 o TD24;<\/li>\n<li><strong>emissione fatture passive<\/strong>, invece, ricevute in modalit\u00e0 analogica dai fornitori esteri, il cliente italiano dovr\u00e0 generare un documento elettronico di tipo TD17, TD18 e TD19, da trasmettere al Sistema di Interscambio.<\/li>\n<\/ul>\n<h1><b>Tipologia dei documenti<\/b><\/h1>\n<p>Di seguito riepiloghiamo i codici-tipo-documento interessati dalla nuova normativa:<\/p>\n<ul>\n<li><strong>Codice-tipo-documento TD17<\/strong> per gli acquisti di servizi dall\u2019estero, per i quali il cliente italiano \u00e8 debitore d\u2019imposta ai sensi dell\u2019art. 17, comma 2, del D.P.R. n. 633\/1972 ed \u00e8, quindi, tenuto ad applicare l\u2019IVA con la procedura di integrazione o di autofatturazione, a seconda che il fornitore sia stabilito in altro Paese UE o in un Paese extra-UE.<\/li>\n<li><strong>Codice-tipo-documento TD18<\/strong> si riferisce agli acquisti intracomunitari di beni per i quali il cessionario italiano \u00e8 tenuto ad applicare l\u2019imposta con la procedura di integrazione di cui all\u2019art. 46 del D.L. n. 331\/1993.<\/li>\n<li><strong>Codice-tipo-documento TD19<\/strong> per gli acquisti di beni dall\u2019estero, per i quali il cliente italiano \u00e8 debitore d\u2019imposta ai sensi dell\u2019art. 17, comma 2, del D.P.R. n. 633\/1972 ed \u00e8, quindi, tenuto ad applicare l\u2019IVA con la procedura di integrazione o di autofatturazione, a seconda che il fornitore sia stabilito in altro Paese UE o in un Paese extra-UE.<\/li>\n<\/ul>\n<\/div><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-margin-top-small:12px;--awb-margin-right-small:0px;--awb-margin-bottom-small:24px;--awb-margin-left-small:0px;\"><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:54;line-height:1.14;\">Sanzioni previste<\/h2><\/div><div class=\"fusion-text fusion-text-3\"><p>E\u2019 prevista una sanzione applicabile alle operazioni effettuate dal 1\u00b0 gennaio 2022 fissata nella misura di 2 euro per ciascuna fattura, entro il limite massimo di 400 euro mensili.<\/p>\n<p>La sanzione \u00e8 ridotta alla met\u00e0, entro il limite massimo di 200 euro mensili, se la trasmissione \u00e8 effettuata entro i 15 giorni successivi alle scadenze o se, nel medesimo termine, \u00e8 effettuata la trasmissione corretta dei dati.<\/p>\n<\/div><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-margin-top-small:12px;--awb-margin-right-small:0px;--awb-margin-bottom-small:24px;--awb-margin-left-small:0px;\"><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:54;line-height:1.14;\">Come verificare se la tua azienda ha gi\u00e0 gli strumenti giusti<\/h2><\/div><div class=\"elegant-empty-space space-vertical fusion-clearfix \" style=\"height:48px;\"><\/div><div class=\"fusion-text fusion-text-4\"><p>Per verificare se il tuo ERP \u00e8 gi\u00e0 in grado di generare e gestire questi documenti elettronici o se siano necessarie attivit\u00e0 di aggiornamento software, di impostazione e configurazione del sistema, ti invitiamo a contattare il consulente che ti supporta abitualmente nell\u2019ambito delle tematiche contabili e fiscali.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":55561,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7195],"tags":[],"class_list":["post-55557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novita-fiscali"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abolizione dell\u2019esterometro: dal 1\u00b0 gennaio cosa cambia<\/title>\n<meta name=\"description\" content=\"La trasmissione dei dati della fattura elettronica tramite SDI diventa necessaria anche per le fatture relative a operazioni transfrontaliere.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abolizione dell\u2019esterometro: dal 1\u00b0 gennaio cosa cambiaData Loss Prevention: cos&#039;\u00e8 e come implementarla in azienda\" \/>\n<meta property=\"og:description\" content=\"Abolizione dell\u2019esterometro: dal 1\u00b0 gennaio cosa cambia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/\" \/>\n<meta property=\"og:site_name\" content=\"Magazine\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-02T10:20:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-02T11:20:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.smeup.com\/magazine\/wp-content\/uploads\/sites\/5\/2021\/10\/45687965_low-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"stefaniatromba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"stefaniatromba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/abolizione-esterometro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/abolizione-esterometro\\\/\"},\"author\":{\"name\":\"stefaniatromba\",\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/#\\\/schema\\\/person\\\/216996ae30f9cc30711b3962b6dfeb7e\"},\"headline\":\"Abolizione dell\u2019esterometro: dal 1\u00b0 gennaio cosa cambia\",\"datePublished\":\"2021-11-02T10:20:49+00:00\",\"dateModified\":\"2021-12-02T11:20:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/abolizione-esterometro\\\/\"},\"wordCount\":2093,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/abolizione-esterometro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/10\\\/45687965_low.jpg\",\"articleSection\":[\"Novit\u00e0 fiscali\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/abolizione-esterometro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/abolizione-esterometro\\\/\",\"url\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/abolizione-esterometro\\\/\",\"name\":\"Abolizione dell\u2019esterometro: dal 1\u00b0 gennaio cosa cambia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/abolizione-esterometro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/abolizione-esterometro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/10\\\/45687965_low.jpg\",\"datePublished\":\"2021-11-02T10:20:49+00:00\",\"dateModified\":\"2021-12-02T11:20:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/#\\\/schema\\\/person\\\/216996ae30f9cc30711b3962b6dfeb7e\"},\"description\":\"La trasmissione dei dati della fattura elettronica tramite SDI diventa necessaria anche per le fatture relative a operazioni transfrontaliere.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/abolizione-esterometro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/abolizione-esterometro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/abolizione-esterometro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/10\\\/45687965_low.jpg\",\"contentUrl\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/10\\\/45687965_low.jpg\",\"width\":2500,\"height\":1668,\"caption\":\"Abolizione Esterometro gennaio 2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/abolizione-esterometro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abolizione dell\u2019esterometro: dal 1\u00b0 gennaio cosa cambia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/#website\",\"url\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/\",\"name\":\"Magazine\",\"description\":\"smeup\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/#\\\/schema\\\/person\\\/216996ae30f9cc30711b3962b6dfeb7e\",\"name\":\"stefaniatromba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aabd12e83cb97696f14351323daee0323a9a2d451bd119a009f7831c3cb538b6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aabd12e83cb97696f14351323daee0323a9a2d451bd119a009f7831c3cb538b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aabd12e83cb97696f14351323daee0323a9a2d451bd119a009f7831c3cb538b6?s=96&d=mm&r=g\",\"caption\":\"stefaniatromba\"},\"url\":\"https:\\\/\\\/www.smeup.com\\\/magazine\\\/blog\\\/author\\\/stefaniatromba\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abolizione dell\u2019esterometro: dal 1\u00b0 gennaio cosa cambia","description":"La trasmissione dei dati della fattura elettronica tramite SDI diventa necessaria anche per le fatture relative a operazioni transfrontaliere.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/","og_locale":"it_IT","og_type":"article","og_title":"Abolizione dell\u2019esterometro: dal 1\u00b0 gennaio cosa cambiaData Loss Prevention: cos'\u00e8 e come implementarla in azienda","og_description":"Abolizione dell\u2019esterometro: dal 1\u00b0 gennaio cosa cambia","og_url":"https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/","og_site_name":"Magazine","article_published_time":"2021-11-02T10:20:49+00:00","article_modified_time":"2021-12-02T11:20:40+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.smeup.com\/magazine\/wp-content\/uploads\/sites\/5\/2021\/10\/45687965_low-1024x683.jpg","type":"image\/jpeg"}],"author":"stefaniatromba","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"stefaniatromba","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/#article","isPartOf":{"@id":"https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/"},"author":{"name":"stefaniatromba","@id":"https:\/\/www.smeup.com\/magazine\/#\/schema\/person\/216996ae30f9cc30711b3962b6dfeb7e"},"headline":"Abolizione dell\u2019esterometro: dal 1\u00b0 gennaio cosa cambia","datePublished":"2021-11-02T10:20:49+00:00","dateModified":"2021-12-02T11:20:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/"},"wordCount":2093,"commentCount":0,"image":{"@id":"https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smeup.com\/magazine\/wp-content\/uploads\/sites\/5\/2021\/10\/45687965_low.jpg","articleSection":["Novit\u00e0 fiscali"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/","url":"https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/","name":"Abolizione dell\u2019esterometro: dal 1\u00b0 gennaio cosa cambia","isPartOf":{"@id":"https:\/\/www.smeup.com\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/#primaryimage"},"image":{"@id":"https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smeup.com\/magazine\/wp-content\/uploads\/sites\/5\/2021\/10\/45687965_low.jpg","datePublished":"2021-11-02T10:20:49+00:00","dateModified":"2021-12-02T11:20:40+00:00","author":{"@id":"https:\/\/www.smeup.com\/magazine\/#\/schema\/person\/216996ae30f9cc30711b3962b6dfeb7e"},"description":"La trasmissione dei dati della fattura elettronica tramite SDI diventa necessaria anche per le fatture relative a operazioni transfrontaliere.","breadcrumb":{"@id":"https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/#primaryimage","url":"https:\/\/www.smeup.com\/magazine\/wp-content\/uploads\/sites\/5\/2021\/10\/45687965_low.jpg","contentUrl":"https:\/\/www.smeup.com\/magazine\/wp-content\/uploads\/sites\/5\/2021\/10\/45687965_low.jpg","width":2500,"height":1668,"caption":"Abolizione Esterometro gennaio 2022"},{"@type":"BreadcrumbList","@id":"https:\/\/www.smeup.com\/magazine\/blog\/abolizione-esterometro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.smeup.com\/magazine\/"},{"@type":"ListItem","position":2,"name":"Abolizione dell\u2019esterometro: dal 1\u00b0 gennaio cosa cambia"}]},{"@type":"WebSite","@id":"https:\/\/www.smeup.com\/magazine\/#website","url":"https:\/\/www.smeup.com\/magazine\/","name":"Magazine","description":"smeup","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.smeup.com\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.smeup.com\/magazine\/#\/schema\/person\/216996ae30f9cc30711b3962b6dfeb7e","name":"stefaniatromba","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/aabd12e83cb97696f14351323daee0323a9a2d451bd119a009f7831c3cb538b6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aabd12e83cb97696f14351323daee0323a9a2d451bd119a009f7831c3cb538b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aabd12e83cb97696f14351323daee0323a9a2d451bd119a009f7831c3cb538b6?s=96&d=mm&r=g","caption":"stefaniatromba"},"url":"https:\/\/www.smeup.com\/magazine\/blog\/author\/stefaniatromba\/"}]}},"_links":{"self":[{"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/posts\/55557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/comments?post=55557"}],"version-history":[{"count":6,"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/posts\/55557\/revisions"}],"predecessor-version":[{"id":55674,"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/posts\/55557\/revisions\/55674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/media\/55561"}],"wp:attachment":[{"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/media?parent=55557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/categories?post=55557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smeup.com\/magazine\/wp-json\/wp\/v2\/tags?post=55557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}